{"id":24301,"date":"2019-07-03T13:11:53","date_gmt":"2019-07-03T11:11:53","guid":{"rendered":"http:\/\/tierheim-moers.de\/Wordpress\/?p=24301"},"modified":"2019-07-03T21:36:41","modified_gmt":"2019-07-03T19:36:41","slug":"fundkater-katze-aus-krefeld-25-04-2019","status":"publish","type":"post","link":"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/","title":{"rendered":"Figaro &#8211; aktiv, \u00fcberm\u00fctig, neugierig, vermittelt 03.07.2019"},"content":{"rendered":"<p><a href=\"http:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro6.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-25344\" src=\"http:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro6-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro6-300x225.jpg 300w, https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro6-768x576.jpg 768w, https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro6-1024x768.jpg 1024w, https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro6-600x450.jpg 600w, https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro6-700x525.jpg 700w, https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro6.jpg 1440w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro5.jpg\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-25343\" src=\"http:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro5-265x300.jpg\" alt=\"\" width=\"265\" height=\"300\" srcset=\"https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro5-265x300.jpg 265w, https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro5-768x869.jpg 768w, https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro5-905x1024.jpg 905w, https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro5-600x679.jpg 600w, https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro5-700x792.jpg 700w, https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro5.jpg 1414w\" sizes=\"(max-width: 265px) 100vw, 265px\" \/><\/a>\n<table id=\"tablepress-206F19\" class=\"tablepress tablepress-id-206F19\">\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-1\">\n\t<td class=\"column-1\">Name des Tiers:<\/td><td class=\"column-2\">Figaro<\/td>\n<\/tr>\n<tr class=\"row-2\">\n\t<td class=\"column-1\">Bestandsnummer:<\/td><td class=\"column-2\">206 F 19<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">Aufnahmegrund:<\/td><td class=\"column-2\">Fundtier<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">Im Tierheim seit:<\/td><td class=\"column-2\">25.04.2019<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">Rasse:<\/td><td class=\"column-2\">EKH<\/td>\n<\/tr>\n<tr class=\"row-6\">\n\t<td class=\"column-1\">Geschlecht:<\/td><td class=\"column-2\">m\u00e4nnlich, kastriert<\/td>\n<\/tr>\n<tr class=\"row-7\">\n\t<td class=\"column-1\">Farbe\/Felll\u00e4nge:<\/td><td class=\"column-2\">schwarz-wei\u00df<\/td>\n<\/tr>\n<tr class=\"row-8\">\n\t<td class=\"column-1\">Geburtsdatum:<\/td><td class=\"column-2\">ca. 2018<\/td>\n<\/tr>\n<tr class=\"row-9\">\n\t<td class=\"column-1\">Schulterh\u00f6he\/Gewicht:<\/td><td class=\"column-2\"><\/td>\n<\/tr>\n<tr class=\"row-10\">\n\t<td class=\"column-1\">Fundort\/Abgabegrund:<\/td><td class=\"column-2\">Krefeld, K\u00f6lner Str. <\/td>\n<\/tr>\n<tr class=\"row-11\">\n\t<td class=\"column-1\">Tierbeschreibung:<\/td><td class=\"column-2\">sehr verschmust, Freig\u00e4nger<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-206F19 from cache --><\/p>\n<p>26.06.2019<\/p>\n<p>Wieso ist Figaro eigentlich noch bei uns?\u00a0 Wir wissen es nicht. Er ist ein ganz toller, verschmuster und lieber Geselle und w\u00e4re auch f\u00fcr verst\u00e4ndige Kinder ein freundlicher Begleiter durch das Leben. Figaro spielt gerne und freut sich \u00fcber Ansprache und Besch\u00e4ftigung. Daher sollte er nur f\u00fcr eine \u00fcberschaubare Zeit alleine sein. Als Familienmitglied w\u00fcrde er einen Haushalt prima erg\u00e4nzen.<\/p>\n<p>12.05.2019<\/p>\n<p>Figaro ist ins Katzenhaus umgezogen. Hier zeigt er sich sehr aktiv, verspielt , tobt durchs Au\u00dfengehege und begr\u00fc\u00dft alle Menschen mit offenem Entgegenkommen. Figaro braucht Menschen, bei denen er aktiv am Alltag teilnehmen kann und die ihm die M\u00f6glichkeit zum Freigang bieten.<\/p>\n<p>30.04.2019<\/p>\n<p>Nach der Eingangsuntersuchung wissen wir nun, dass es sich hier um einen kastrierten Kater handelt. Wir haben ihn Figaro genannt.<\/p>\n<p>26.04.2019<\/p>\n<p>Dieser wahrscheinlich Fundkater (muss noch genau kontrolliert werden, auch ob kastriert,\u00a0 gerade nicht sehr kooperativ) wurde gestern in Krefeld gesichert. Er ist nicht gechipt. Weitere Infos werden so schnell wie m\u00f6glich erg\u00e4nzt. Wer ihn vermisst, kann sich ans Tierheim wenden.<\/p>\n<div class=\"shariff shariff-align-flex-start shariff-widget-align-center\" data-url=\"https%3A%2F%2Ftierheim-moers.de%2FWordpress%2Ffundkater-katze-aus-krefeld-25-04-2019%2F\" data-timestamp=\"1562189801\" data-hidezero=\"1\" data-backendurl=\"https:\/\/tierheim-moers.de\/Wordpress\/wp-json\/shariff\/v1\/share_counts?\"><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-small\"><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Ftierheim-moers.de%2FWordpress%2Ffundkater-katze-aus-krefeld-25-04-2019%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Ftierheim-moers.de%2FWordpress%2Ffundkater-katze-aus-krefeld-25-04-2019%2F&text=Figaro%20%E2%80%93%20aktiv%2C%20%C3%BCberm%C3%BCtig%2C%20neugierig%2C%20vermittelt%2003.07.2019\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button whatsapp shariff-nocustomcolor\" style=\"background-color:#5cbe4a\"><a href=\"https:\/\/api.whatsapp.com\/send?text=https%3A%2F%2Ftierheim-moers.de%2FWordpress%2Ffundkater-katze-aus-krefeld-25-04-2019%2F%20Figaro%20%E2%80%93%20aktiv%2C%20%C3%BCberm%C3%BCtig%2C%20neugierig%2C%20vermittelt%2003.07.2019\" title=\"Bei Whatsapp teilen\" aria-label=\"Bei Whatsapp teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#34af23; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#34af23\" d=\"M17.6 17.4q0.2 0 1.7 0.8t1.6 0.9q0 0.1 0 0.3 0 0.6-0.3 1.4-0.3 0.7-1.3 1.2t-1.8 0.5q-1 0-3.4-1.1-1.7-0.8-3-2.1t-2.6-3.3q-1.3-1.9-1.3-3.5v-0.1q0.1-1.6 1.3-2.8 0.4-0.4 0.9-0.4 0.1 0 0.3 0t0.3 0q0.3 0 0.5 0.1t0.3 0.5q0.1 0.4 0.6 1.6t0.4 1.3q0 0.4-0.6 1t-0.6 0.8q0 0.1 0.1 0.3 0.6 1.3 1.8 2.4 1 0.9 2.7 1.8 0.2 0.1 0.4 0.1 0.3 0 1-0.9t0.9-0.9zM14 26.9q2.3 0 4.3-0.9t3.6-2.4 2.4-3.6 0.9-4.3-0.9-4.3-2.4-3.6-3.6-2.4-4.3-0.9-4.3 0.9-3.6 2.4-2.4 3.6-0.9 4.3q0 3.6 2.1 6.6l-1.4 4.2 4.3-1.4q2.8 1.9 6.2 1.9zM14 2.2q2.7 0 5.2 1.1t4.3 2.9 2.9 4.3 1.1 5.2-1.1 5.2-2.9 4.3-4.3 2.9-5.2 1.1q-3.5 0-6.5-1.7l-7.4 2.4 2.4-7.2q-1.9-3.2-1.9-6.9 0-2.7 1.1-5.2t2.9-4.3 4.3-2.9 5.2-1.1z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button sms shariff-nocustomcolor shariff-mobile\" style=\"background-color:#d7d9d8\"><a href=\"sms:?&body=https%3A%2F%2Ftierheim-moers.de%2FWordpress%2Ffundkater-katze-aus-krefeld-25-04-2019%2F\" title=\"Per SMS teilen\" aria-label=\"Per SMS teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#a1e877; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"510\" height=\"510\" viewBox=\"0 0 510 510\"><path fill=\"#a1e877\" d=\"M459 0H51C23 0 0 23 0 51v459l102-102h357c28.1 0 51-22.9 51-51V51C510 23 487.1 0 459 0zM178.5 229.5h-51v-51h51V229.5zM280.5 229.5h-51v-51h51V229.5zM382.5 229.5h-51v-51h51V229.5z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>26.06.2019 Wieso ist Figaro eigentlich noch bei uns?\u00a0 Wir wissen es nicht. Er ist ein ganz toller, verschmuster und lieber Geselle und w\u00e4re auch f\u00fcr verst\u00e4ndige Kinder ein freundlicher Begleiter durch das Leben. Figaro spielt gerne und freut sich \u00fcber Ansprache und Besch\u00e4ftigung. Daher sollte er nur f\u00fcr eine \u00fcberschaubare &#8230;<\/p>\n","protected":false},"author":4,"featured_media":25343,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-24301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vermittelt","column","threecol","has-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Figaro - aktiv, \u00fcberm\u00fctig, neugierig, vermittelt 03.07.2019 | TIERHEIM MOERS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Figaro - aktiv, \u00fcberm\u00fctig, neugierig, vermittelt 03.07.2019 | TIERHEIM MOERS\" \/>\n<meta property=\"og:description\" content=\"26.06.2019 Wieso ist Figaro eigentlich noch bei uns?\u00a0 Wir wissen es nicht. Er ist ein ganz toller, verschmuster und lieber Geselle und &#8230;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"TIERHEIM MOERS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/de-de.facebook.com\/moers.tierheim\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-03T11:11:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-03T19:36:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1414\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gisela Kuhnen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gisela Kuhnen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/\"},\"author\":{\"name\":\"Gisela Kuhnen\",\"@id\":\"https:\/\/tierheim-moers.de\/Wordpress\/#\/schema\/person\/35ad410ed2d8620d4f57f813585b0d8e\"},\"headline\":\"Figaro &#8211; aktiv, \u00fcberm\u00fctig, neugierig, vermittelt 03.07.2019\",\"datePublished\":\"2019-07-03T11:11:53+00:00\",\"dateModified\":\"2019-07-03T19:36:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/\"},\"wordCount\":183,\"publisher\":{\"@id\":\"https:\/\/tierheim-moers.de\/Wordpress\/#organization\"},\"image\":{\"@id\":\"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro5.jpg\",\"articleSection\":[\"Vermittelt\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/\",\"url\":\"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/\",\"name\":\"Figaro - aktiv, \u00fcberm\u00fctig, neugierig, vermittelt 03.07.2019 | TIERHEIM MOERS\",\"isPartOf\":{\"@id\":\"https:\/\/tierheim-moers.de\/Wordpress\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro5.jpg\",\"datePublished\":\"2019-07-03T11:11:53+00:00\",\"dateModified\":\"2019-07-03T19:36:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/#primaryimage\",\"url\":\"https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro5.jpg\",\"contentUrl\":\"https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro5.jpg\",\"width\":1414,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/tierheim-moers.de\/Wordpress\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Figaro &#8211; aktiv, \u00fcberm\u00fctig, neugierig, vermittelt 03.07.2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tierheim-moers.de\/Wordpress\/#website\",\"url\":\"https:\/\/tierheim-moers.de\/Wordpress\/\",\"name\":\"Tierheim Moers\",\"description\":\"Tierheim | Hundepension | Tierschutz | Moers\",\"publisher\":{\"@id\":\"https:\/\/tierheim-moers.de\/Wordpress\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tierheim-moers.de\/Wordpress\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tierheim-moers.de\/Wordpress\/#organization\",\"name\":\"Tierheim Moers\",\"url\":\"https:\/\/tierheim-moers.de\/Wordpress\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/tierheim-moers.de\/Wordpress\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2014\/04\/Logo-TSV-Moers-V01-RGB-300.png\",\"contentUrl\":\"https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2014\/04\/Logo-TSV-Moers-V01-RGB-300.png\",\"width\":1052,\"height\":1038,\"caption\":\"Tierheim Moers\"},\"image\":{\"@id\":\"https:\/\/tierheim-moers.de\/Wordpress\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/de-de.facebook.com\/moers.tierheim\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/tierheim-moers.de\/Wordpress\/#\/schema\/person\/35ad410ed2d8620d4f57f813585b0d8e\",\"name\":\"Gisela Kuhnen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/tierheim-moers.de\/Wordpress\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/807ca84b4538291e2f5dc665ed240a0d4d7ab8f22360ec427a82fe926980b31a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/807ca84b4538291e2f5dc665ed240a0d4d7ab8f22360ec427a82fe926980b31a?s=96&d=mm&r=g\",\"caption\":\"Gisela Kuhnen\"},\"url\":\"https:\/\/tierheim-moers.de\/Wordpress\/author\/gisela-kuhnen\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Figaro - aktiv, \u00fcberm\u00fctig, neugierig, vermittelt 03.07.2019 | TIERHEIM MOERS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/","og_locale":"de_DE","og_type":"article","og_title":"Figaro - aktiv, \u00fcberm\u00fctig, neugierig, vermittelt 03.07.2019 | TIERHEIM MOERS","og_description":"26.06.2019 Wieso ist Figaro eigentlich noch bei uns?\u00a0 Wir wissen es nicht. Er ist ein ganz toller, verschmuster und lieber Geselle und &#8230;","og_url":"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/","og_site_name":"TIERHEIM MOERS","article_publisher":"https:\/\/de-de.facebook.com\/moers.tierheim","article_published_time":"2019-07-03T11:11:53+00:00","article_modified_time":"2019-07-03T19:36:41+00:00","og_image":[{"width":1414,"height":1600,"url":"https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro5.jpg","type":"image\/jpeg"}],"author":"Gisela Kuhnen","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Gisela Kuhnen","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/#article","isPartOf":{"@id":"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/"},"author":{"name":"Gisela Kuhnen","@id":"https:\/\/tierheim-moers.de\/Wordpress\/#\/schema\/person\/35ad410ed2d8620d4f57f813585b0d8e"},"headline":"Figaro &#8211; aktiv, \u00fcberm\u00fctig, neugierig, vermittelt 03.07.2019","datePublished":"2019-07-03T11:11:53+00:00","dateModified":"2019-07-03T19:36:41+00:00","mainEntityOfPage":{"@id":"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/"},"wordCount":183,"publisher":{"@id":"https:\/\/tierheim-moers.de\/Wordpress\/#organization"},"image":{"@id":"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro5.jpg","articleSection":["Vermittelt"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/","url":"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/","name":"Figaro - aktiv, \u00fcberm\u00fctig, neugierig, vermittelt 03.07.2019 | TIERHEIM MOERS","isPartOf":{"@id":"https:\/\/tierheim-moers.de\/Wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/#primaryimage"},"image":{"@id":"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro5.jpg","datePublished":"2019-07-03T11:11:53+00:00","dateModified":"2019-07-03T19:36:41+00:00","breadcrumb":{"@id":"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/#primaryimage","url":"https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro5.jpg","contentUrl":"https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2019\/06\/fk-figaro5.jpg","width":1414,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/tierheim-moers.de\/Wordpress\/fundkater-katze-aus-krefeld-25-04-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/tierheim-moers.de\/Wordpress\/"},{"@type":"ListItem","position":2,"name":"Figaro &#8211; aktiv, \u00fcberm\u00fctig, neugierig, vermittelt 03.07.2019"}]},{"@type":"WebSite","@id":"https:\/\/tierheim-moers.de\/Wordpress\/#website","url":"https:\/\/tierheim-moers.de\/Wordpress\/","name":"Tierheim Moers","description":"Tierheim | Hundepension | Tierschutz | Moers","publisher":{"@id":"https:\/\/tierheim-moers.de\/Wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tierheim-moers.de\/Wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/tierheim-moers.de\/Wordpress\/#organization","name":"Tierheim Moers","url":"https:\/\/tierheim-moers.de\/Wordpress\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tierheim-moers.de\/Wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2014\/04\/Logo-TSV-Moers-V01-RGB-300.png","contentUrl":"https:\/\/tierheim-moers.de\/Wordpress\/wp-content\/uploads\/2014\/04\/Logo-TSV-Moers-V01-RGB-300.png","width":1052,"height":1038,"caption":"Tierheim Moers"},"image":{"@id":"https:\/\/tierheim-moers.de\/Wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/de-de.facebook.com\/moers.tierheim"]},{"@type":"Person","@id":"https:\/\/tierheim-moers.de\/Wordpress\/#\/schema\/person\/35ad410ed2d8620d4f57f813585b0d8e","name":"Gisela Kuhnen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tierheim-moers.de\/Wordpress\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/807ca84b4538291e2f5dc665ed240a0d4d7ab8f22360ec427a82fe926980b31a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/807ca84b4538291e2f5dc665ed240a0d4d7ab8f22360ec427a82fe926980b31a?s=96&d=mm&r=g","caption":"Gisela Kuhnen"},"url":"https:\/\/tierheim-moers.de\/Wordpress\/author\/gisela-kuhnen\/"}]}},"_links":{"self":[{"href":"https:\/\/tierheim-moers.de\/Wordpress\/wp-json\/wp\/v2\/posts\/24301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tierheim-moers.de\/Wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tierheim-moers.de\/Wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tierheim-moers.de\/Wordpress\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/tierheim-moers.de\/Wordpress\/wp-json\/wp\/v2\/comments?post=24301"}],"version-history":[{"count":7,"href":"https:\/\/tierheim-moers.de\/Wordpress\/wp-json\/wp\/v2\/posts\/24301\/revisions"}],"predecessor-version":[{"id":25458,"href":"https:\/\/tierheim-moers.de\/Wordpress\/wp-json\/wp\/v2\/posts\/24301\/revisions\/25458"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tierheim-moers.de\/Wordpress\/wp-json\/wp\/v2\/media\/25343"}],"wp:attachment":[{"href":"https:\/\/tierheim-moers.de\/Wordpress\/wp-json\/wp\/v2\/media?parent=24301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tierheim-moers.de\/Wordpress\/wp-json\/wp\/v2\/categories?post=24301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tierheim-moers.de\/Wordpress\/wp-json\/wp\/v2\/tags?post=24301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}